{"id":2,"count":2,"description":"","link":"http:\/\/jellydemos.com\/wordpress\/muziq\/revolutionslider\/category\/music\/","name":"Music","slug":"music","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"http:\/\/jellydemos.com\/wordpress\/muziq\/revolutionslider\/wp-json\/wp\/v2\/categories\/2","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/jellydemos.com\/wordpress\/muziq\/revolutionslider\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/jellydemos.com\/wordpress\/muziq\/revolutionslider\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/jellydemos.com\/wordpress\/muziq\/revolutionslider\/wp-json\/wp\/v2\/posts?categories=2"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}